{"id":10311,"date":"2026-07-15T07:22:31","date_gmt":"2026-07-15T06:22:31","guid":{"rendered":"https:\/\/www.koertkrouwel.com\/index.php\/2026\/07\/15\/15-juli-2026-von-der-lugen-is-in-kiev\/"},"modified":"2026-07-15T07:22:31","modified_gmt":"2026-07-15T06:22:31","slug":"15-juli-2026-von-der-lugen-is-in-kiev","status":"publish","type":"post","link":"https:\/\/www.koertkrouwel.com\/index.php\/2026\/07\/15\/15-juli-2026-von-der-lugen-is-in-kiev\/","title":{"rendered":"15 juli 2026, von der lugen is in Kiev."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Waarom laten de Poetin dat toe? Er zijn veel Russen die zich dat afvragen. Er zijn veel Russen die zich afvragen waarom er geen Oreshnik&#8217;s richting London en Rotterdam worden afgevuurd. Ze zijn er wel klaar mee, ik kan het me voorstellen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Barbaren noemen ze ons. Bapbap in het Russisch. Lula, de president van Brazili\u00eb, noemde Trumpfius en consorten piraten, we zijn terug in de tijd, het westen heeft het alleen niet door. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">China blijft rustig achterover leunen, kijkt de kat uit de boom en verscheept nog wat meer rotzooi naar Europa. Iran is niet meer bang, gaat er vol voor. Afrika trapt ons het continent uit. De wereld verandert maar wij willen het niet zien, zoeken niet naar oplossingen maar houden vast aan een illusie, te bang te verliezen wat we denken te hebben. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoe gaat het script zich ontvouwen? Feit is dat Edom de pisang is. Gemangeld tussen de beer en de adelaar met op afstand een draak. Waarom zoeken we niet naar de dialoog? Omdat dat niet past in het script&#8230; <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"773\" src=\"https:\/\/i0.wp.com\/www.koertkrouwel.com\/wp-content\/uploads\/2026\/07\/img_20260714_174712_5101166420406522365171.jpg?resize=580%2C773&#038;ssl=1\" alt=\"\" class=\"wp-image-10310\" srcset=\"https:\/\/i0.wp.com\/www.koertkrouwel.com\/wp-content\/uploads\/2026\/07\/img_20260714_174712_5101166420406522365171.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.koertkrouwel.com\/wp-content\/uploads\/2026\/07\/img_20260714_174712_5101166420406522365171.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/www.koertkrouwel.com\/wp-content\/uploads\/2026\/07\/img_20260714_174712_5101166420406522365171.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/www.koertkrouwel.com\/wp-content\/uploads\/2026\/07\/img_20260714_174712_5101166420406522365171.jpg?resize=1200%2C1600&amp;ssl=1 1200w, https:\/\/i0.wp.com\/www.koertkrouwel.com\/wp-content\/uploads\/2026\/07\/img_20260714_174712_5101166420406522365171.jpg?w=1500&amp;ssl=1 1500w\" sizes=\"auto, (max-width: 580px) 100vw, 580px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Waarom laten de Poetin dat toe? Er zijn veel Russen die zich dat afvragen. Er zijn veel Russen die zich afvragen waarom er geen Oreshnik&#8217;s richting London en Rotterdam worden afgevuurd. Ze zijn er wel klaar mee, ik kan het me voorstellen. Barbaren noemen ze ons. Bapbap in het Russisch. Lula, de president van Brazili\u00eb, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-10311","post","type-post","status-publish","format-standard","hentry","category-niet-gecategoriseerd"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/posts\/10311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/comments?post=10311"}],"version-history":[{"count":0,"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/posts\/10311\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/media?parent=10311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/categories?post=10311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.koertkrouwel.com\/index.php\/wp-json\/wp\/v2\/tags?post=10311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}